{"id":20645,"date":"2019-10-07T12:21:10","date_gmt":"2019-10-07T10:21:10","guid":{"rendered":"http:\/\/secondotest.finzipasca.com\/?p=20645"},"modified":"2019-10-07T12:24:21","modified_gmt":"2019-10-07T10:24:21","slug":"great-success-for-einstein-on-the-beach","status":"publish","type":"post","link":"https:\/\/secondotest.finzipasca.com\/fr\/great-success-for-einstein-on-the-beach\/","title":{"rendered":"Grand succ\u00e8s pour l\u2019\u0153uvre  Einstein on the Beach"},"content":{"rendered":"<p><strong>Grand succ\u00e8s pour l\u2019\u0153uvre\u00a0<em>Einstein on the Beach<\/em>, fruit d\u2019une premi\u00e8re coproduction qui signe une remarquable collaboration en Suisse avec le plus important op\u00e9ra de la Suisse Romande, le Grand Th\u00e9\u00e2tre de Gen\u00e8ve<\/strong>. Une relation n\u00e9e du respect r\u00e9ciproque que se portent la Compagnie et le nouveau directeur de l\u2019institution genevoise, Aviel Cahn. La r\u00e9action du public et de la presse a \u00e9t\u00e9 extr\u00eamement positive. <strong>En seulement six repr\u00e9sentations, l\u2019\u0153uvre a r\u00e9uni plus de 7\u00a0200\u00a0spectateurs<\/strong>.<\/p>\n<p><strong><u>Revue de presse<\/u><\/strong><br \/>\n\u00ab\u00a0Un v\u00e9ritable op\u00e9ra \u00e0 machines, comme \u00e0 l&#8217;\u00e9poque baroque, o\u00f9 l&#8217;\u0153il ne sait qu&#8217;admirer le plus, entre la beaut\u00e9 des couleurs, les illusions d&#8217;optique des d\u00e9cors de Hugo Gargiulo, les \u00e9volutions a\u00e9riennes des danseurs et acrobates de la Compagnia Finzi Pasca. Sans oublier une savoureuse touche d&#8217;humour.\u00a0\u00bb<br \/>\n<strong>13.09.2019 &#8211;\u00a0<em>Le Figaro<\/em><\/strong><\/p>\n<p>\u00ab\u00a0L&#8217;op\u00e9ra de Philip Glas et Robert Wilson change radicalement d&#8217;univers avec Daniele Finzi Pasca. Un r\u00eave \u00e9veill\u00e9 ouvre avec succ\u00e8s la premi\u00e8re saison d&#8217;Aviel Cahn \u00e0 Gen\u00e8ve. \u00bb<br \/>\n<strong>13.09.2019 &#8211;<em>\u00a0Le Temps<\/em><\/strong><\/p>\n<p>\u00ab\u00a0En confiant ce d\u00e9fi quasi dantesque \u00e0 Daniele Finzi Pasca, artiste venu du monde circassien et faiseur de grands \u00e9v\u00e9nements populaires, le Suisse op\u00e8re une rupture salutaire avec le p\u00f4le glaciaire wilsonien. Et \u00e7a fonctionne.\u00a0\u00bb<br \/>\n<strong>16.09.2019 &#8211;\u00a0<em>Le Monde<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grand succ\u00e8s pour l\u2019\u0153uvre\u00a0Einstein on the Beach, fruit d\u2019une premi\u00e8re coproduction qui signe une remarquable collaboration en Suisse avec le plus important op\u00e9ra de la Suisse Romande, le Grand Th\u00e9\u00e2tre de Gen\u00e8ve. Une relation n\u00e9e du respect r\u00e9ciproque que se portent la Compagnie et le nouveau directeur de l\u2019institution genevoise, Aviel Cahn. La r\u00e9action du public et de la presse a \u00e9t\u00e9 extr\u00eamement positive. En seulement six repr\u00e9sentations, l\u2019\u0153uvre a r\u00e9uni plus de 7\u00a0200\u00a0spectateurs. Revue de presse \u00ab\u00a0Un v\u00e9ritable op\u00e9ra \u00e0 machines, comme \u00e0 l&#8217;\u00e9poque baroque, o\u00f9 l&#8217;\u0153il ne sait qu&#8217;admirer le plus, entre la beaut\u00e9 des couleurs, les illusions d&#8217;optique des d\u00e9cors de Hugo Gargiulo, les \u00e9volutions a\u00e9riennes des danseurs et acrobates de la Compagnia Finzi Pasca. Sans oublier une savoureuse touche d&#8217;humour.\u00a0\u00bb 13.09.2019 &#8211;\u00a0Le Figaro \u00ab\u00a0L&#8217;op\u00e9ra de Philip Glas et Robert Wilson change radicalement d&#8217;univers avec Daniele Finzi Pasca. Un r\u00eave \u00e9veill\u00e9 ouvre avec succ\u00e8s la premi\u00e8re saison d&#8217;Aviel Cahn \u00e0 Gen\u00e8ve. \u00bb 13.09.2019 &#8211;\u00a0Le Temps \u00ab\u00a0En confiant ce d\u00e9fi quasi dantesque \u00e0 Daniele Finzi Pasca, artiste venu du monde circassien et faiseur de grands \u00e9v\u00e9nements populaires, le Suisse op\u00e8re une rupture salutaire avec le p\u00f4le glaciaire wilsonien. Et \u00e7a fonctionne.\u00a0\u00bb 16.09.2019 &#8211;\u00a0Le Monde &nbsp; &nbsp;<\/p>\n","protected":false},"author":27,"featured_media":20641,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[31],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/secondotest.finzipasca.com\/fr\/wp-json\/wp\/v2\/posts\/20645"}],"collection":[{"href":"https:\/\/secondotest.finzipasca.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/secondotest.finzipasca.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/secondotest.finzipasca.com\/fr\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/secondotest.finzipasca.com\/fr\/wp-json\/wp\/v2\/comments?post=20645"}],"version-history":[{"count":0,"href":"https:\/\/secondotest.finzipasca.com\/fr\/wp-json\/wp\/v2\/posts\/20645\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secondotest.finzipasca.com\/fr\/wp-json\/wp\/v2\/media\/20641"}],"wp:attachment":[{"href":"https:\/\/secondotest.finzipasca.com\/fr\/wp-json\/wp\/v2\/media?parent=20645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/secondotest.finzipasca.com\/fr\/wp-json\/wp\/v2\/categories?post=20645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/secondotest.finzipasca.com\/fr\/wp-json\/wp\/v2\/tags?post=20645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}